﻿{"id":17996,"date":"2025-12-12T16:02:52","date_gmt":"2025-12-12T14:02:52","guid":{"rendered":"https:\/\/iicamsterdam.esteri.it\/?page_id=17996"},"modified":"2026-08-26T11:41:00","modified_gmt":"2026-08-26T09:41:00","slug":"workshop-di-grammatica-2026","status":"publish","type":"page","link":"https:\/\/iicamsterdam.esteri.it\/it\/lingua-e-cultura\/i-corsi-di-lingua\/workshop-di-grammatica-2026\/","title":{"rendered":"Workshop di grammatica 2026-27"},"content":{"rendered":"<p><em><strong>Ami la lingua Italiana e vuoi migliorare o approfondire la tua grammatica?<\/strong><\/em><\/p>\n<p>L&#8217;Istituto di Cultura Italiana offre una serie di sei incontri focalizzati sugli aspetti grammaticali pi\u00f9 utilizzati e allo stesso tempo pi\u00f9 ostici di questa bellissima lingua.<\/p>\n<p>Se vuoi iscriverti a tutti i 8 incontri <a href=\"https:\/\/iicamsterdam.scuolasemplice.it\/selling\/public\/CEvX15iomp#\/\">clicca qui<\/a><\/p>\n<p>Se vuoi iscriverti al singolo incontro clicca sul link indicato in ogni workshop.<\/p>\n<p>&nbsp;<\/p>\n<h2>Programma dei workshop:<\/h2>\n<p><strong>Marted\u00ec 6 ottobre &#8211; dalle 10:30 alle 12:30<br \/>\n<\/strong><strong><strong>I Comparativi &#8211; <strong><em>Pi\u00f9 facile di quanto pensi. Meno complicato di quanto sembri. <\/em><\/strong><strong><em>\ud83d\ude09 (New)<\/em><\/strong><\/strong><\/strong><\/p>\n<p>I comparativi sono ovunque: quando scegli un ristorante, confronti due citt\u00e0, descrivi una persona o&#8230; discuti su quale sia la pizza migliore! \ud83c\udf55\ud83d\ude04<\/p>\n<p>Ma quando usare pi\u00f9, meno, migliore, peggiore o come?<\/p>\n<p>Se ogni volta ti fermi a pensarci, questo workshop \u00e8 quello che fa per te!<\/p>\n<p>In questo\u00a0workshop\u00a0di due\u00a0ore, l&#8217;insegnante\u00a0Monica Ercolano vi\u00a0guider\u00e0, attraverso tanta pratica, esempi reali e attivit\u00e0 interattive, nel utilizzare\u00a0i comparativi in modo naturale.<\/p>\n<p>Questo workshop \u00e8 aperto a chi abbia completato un livello A2 e a chi, anche con un livello pi\u00f9 alto, voglia approfondire o rivedere l&#8217;utilizzo dei comparativi<\/p>\n<p>Vuoi partecipare a questo incontro?<a href=\"https:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/JMWViuUQaa#\/\"> Iscriviti qui\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Marted\u00ec 3 novembre &#8211; dalle 10:30 alle 12:30<br \/>\n<\/strong><\/p>\n<p><strong>Passato Prossimo e Imperfetto<\/strong><\/p>\n<p>Molto spesso ci troviamo a parlare di esperienze o situazioni passate, ma non e` sempre facile distinguere quando usare il passato prossimo e quando usare l&#8217;imperfetto.<\/p>\n<p>In questo\u00a0workshop\u00a0di due\u00a0ore, l&#8217;insegnante\u00a0Monica Ercolano vi\u00a0guidera` ad analizzare le strutture e a praticare l&#8217;utilizzo di queste due forme di tempo passato.<\/p>\n<p>Questo workshop \u00e8 aperto a chi abbia un livello A2 e a chi, anche con un livello pi\u00f9 alto, voglia approfondire o rivedere l&#8217;utilizzo di queste due forme di tempo passato.<\/p>\n<p>Vuoi partecipare a questo incontro? <a href=\"http:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/0WgSElj3uj\">Iscriviti qui<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Marted\u00ec 1 dicembre &#8211; dalle 10:30 alle 12:30<br \/>\n<\/strong><\/p>\n<p><strong>Il Condizionale (<em>New<\/em>)<\/strong><\/p>\n<p>Per smettere di dire solo <em><strong>voglio<\/strong><\/em> e iniziare a dire <em><strong>vorrei<\/strong><\/em> (e sembrare subito pi\u00f9 naturale \ud83d\ude09).<\/p>\n<p>In questo\u00a0workshop\u00a0di due\u00a0ore, guidato dall&#8217;insegnante\u00a0Monica Ercolano, imparerai a esprimere desideri, dare consigli, fare richieste con gentilezza e parlare di situazioni ipotetiche come un vero italiano.<\/p>\n<p>Questo workshop \u00e8 aperto a chi abbia un livello A2+ e a chi, anche con un livello pi\u00f9 alto, voglia approfondire o rivedere l&#8217;utilizzo di questa forma verbale<\/p>\n<p>Vuoi partecipare a questo incontro? <a href=\"http:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/PZEadTx7AQ\">Iscriviti qui<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Marted\u00ec 12 gennaio &#8211; dalle 10:30 alle 12:30<br \/>\n<\/strong><\/p>\n<p><strong>Il Periodo Ipotetico<\/strong><\/p>\n<p><strong><em>Se tu fossi iscritto al corso, parleresti come un madrelingua<\/em><\/strong><em>.<\/em><\/p>\n<p>Ma puoi ancora farlo!<\/p>\n<p>Scopri tutti i segreti del periodo ipotetico e divertiti a usarlo.<\/p>\n<p>In questo\u00a0workshop\u00a0di due ore, l&#8217;insegnante Monica Ercolano vi\u00a0mostrer\u00e0 come esprimere ipotesi, sogni e desideri con naturalezza.<\/p>\n<p>Questo workshop \u00e8 aperto a chi abbia completato come minimo un livello B1 e a chi, anche con un livello pi\u00f9 alto, voglia approfondire o rivedere l&#8217;utilizzo di questa forma grammaticale.<\/p>\n<p>Vuoi partecipare a questo incontro? <a href=\"http:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/GWywOaOn17\">Iscriviti qui\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Marted\u00ec 9 febbraio &#8211; dalle 10:30 alle 12:30<br \/>\n<\/strong><\/p>\n<p><strong>Le Forme Impersonali (<em>New<\/em>)<\/strong><\/p>\n<p>Per capire finalmente perch\u00e9 in Italia <em><strong>si dice<\/strong><\/em><strong>, <em>si fa<\/em> e <em>si mangia<\/em><\/strong>&#8230; anche quando non sai chi lo fa!<\/p>\n<p>In questo\u00a0workshop\u00a0di due ore, guidato dall&#8221;insegnante Monica Ercolano, imparerai a esprimere azioni in modo generale, senza specificare un soggetto (es. &#8220;la gente&#8221;, &#8220;si dice&#8221;). Questo render\u00e0 il tuo parlato pi\u00f9 fluido e ti permetter\u00e0\u00a0di esprimere opinioni, regole e usanze in modo elegante e naturale.<\/p>\n<p>Questo workshop \u00e8 aperto a chi abbia completato un livello B1 e a chi, anche con un livello pi\u00f9 alto, voglia approfondire o rivedere l&#8217;utilizzo delle forme impersonali.<\/p>\n<p>Vuoi partecipare a questo incontro? <a href=\"http:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/CId0WQN5DQ\">Iscriviti qui<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><strong>Marted\u00ec 16 marzo &#8211; dalle 10:30 alle 12:30<\/strong><\/strong><\/p>\n<p style=\"text-align: left;\"><strong>I Pronomi Diretti\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\">\ud83e\udd14 <strong>&#8220;Compro il pane&#8221;&#8230; o &#8220;Lo compro&#8221;?<\/strong><\/p>\n<p style=\"text-align: left;\">Se ogni volta che devi usare <strong>lo, la, li, le<\/strong> ti blocchi un secondo (o dieci \ud83d\ude05), questo workshop \u00e8 per te!<\/p>\n<p style=\"text-align: left;\">In questo\u00a0workshop\u00a0di due ore, guidato dall&#8217;insegnante Monica Ercolano, imparerai a\u00a0sostituire nomi con i pronomi giusti;evitare gli errori pi\u00f9 comuni e a\u00a0parlare con pi\u00f9 scioltezza nelle conversazioni di tutti i giorni.<\/p>\n<p style=\"text-align: left;\">Niente esercizi noiosi da riempire in silenzio: lavoreremo con dialoghi, situazioni reali e tanta pratica, perch\u00e9 i pronomi si imparano&#8230; <strong><em>usandoli<\/em><\/strong>!<\/p>\n<p style=\"text-align: left;\">Questo workshop \u00e8 aperto a chi abbia completato un livello A2 e a chi, anche con un livello pi\u00f9 alto, voglia approfondire o rivedere l&#8217;utilizzo dei pronomi diretti .<\/p>\n<p>Vuoi partecipare a questo incontro?<a href=\"http:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/5FjtC5NXT4\"> Iscriviti qui<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Marted\u00ec 6 aprile &#8211; dalle 10:30 alle 12:30<\/strong><\/p>\n<p><strong>I Pronomi Indiretti<\/strong><\/p>\n<p>\ud83e\udd2f <strong>&#8220;<em>Gli telefono<\/em>&#8220;&#8230; o &#8220;<em>Lo telefono<\/em>&#8220;?<\/strong><br \/>\n\ud83d\ude05 <strong>&#8220;<em>Le scrivo<\/em>&#8220;&#8230; ma perch\u00e9 non posso dire &#8220;<em>la scrivo<\/em>&#8220;?<\/strong><\/p>\n<p>Se i pronomi indiretti ti fanno venire qualche dubbio, sei in ottima compagnia!\u00a0E` proprio per questo motivo che in questo workshop di grammatica. guidato dall&#8217;insegnante Monica Ercolano,\u00a0\u00a0scoprirai come\u00a0dire a chi telefoni, scrivi, rispondi o fai un regalo&#8230; senza ripetere sempre gli stessi nomi, e ti\u00a0sentirti pi\u00f9 sicuro\/a nelle conversazioni di tutti i giorni.<\/p>\n<p>Niente grammatica &#8220;fine a se stessa&#8221;: solo spiegazioni chiare, esempi reali e tanta pratica per usare i pronomi con naturalezza.<\/p>\n<p>Questo\u00a0workshop\u00a0e` aperto a chi abbia completato un livello A2 e a chi anche con un livello pi\u00f9 alto, voglia approfondire o rivedere l&#8217;utilizzo dei pronomi indiretti.<\/p>\n<p>Vuoi partecipare a questo incontro? <a href=\"https:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/5YerMMrPrg#\/\">Iscriviti qui<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Marted\u00ec 11 maggio &#8211; dalle 10:30 alle 12:30<\/strong><\/p>\n<p><strong>I Verbi Pronominali (<em>New<\/em>)<\/strong><\/p>\n<p><em><strong>Andarsene, cavarsela, mettercela tutta<\/strong><\/em><em>&#8230;<\/em> I verbi che all&#8217;inizio sembrano misteriosi diventeranno i tuoi migliori alleati per capire e parlare un italiano davvero vivo e colloquiale.<\/p>\n<p>In questo workshop di grammatica, l&#8217;insegnante Monica Ercolano vi guider\u00e0 nel loro utilizzo e alla fine del workshop saprai padroneggiarli rendendo cos\u00ec il tuo parlato molto pi\u00f9 fluido e autentico come un vero italiano.<\/p>\n<p>Questo\u00a0workshop\u00a0e` aperto a chi abbia completato come minimo un livello B1 e a chi, anche con un livello piu` alto, voglia approfondire o rivedere l&#8217;utilizzo delle preposizioni.<\/p>\n<p>Vuoi partecipare a questo incontro? <a href=\"http:\/\/iicamsterdam.scuolasemplice.it\/classes\/public\/6avqNwAbHL\">Iscriviti qui<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Prezzo dei workshop<\/strong><\/h3>\n<p>L&#8217;iscrizione all&#8217;intera serie di workshop ha un costo di\u00a0 <strong>\u20ac 300,00.<br \/>\n<\/strong>Puoi partecipare a un singolo workshop al costo di <strong>\u20ac 45,00 <\/strong>a sessione.<br \/>\nNel prezzo del corso \u00e8 compreso il materiale, che sar\u00e0 fornito dalla docente.<br \/>\nTutti gli iscritti saranno automaticamente tesserati della nostra\u00a0<a href=\"https:\/\/iicamsterdam.esteri.it\/it\/lingua-e-cultura\/biblioteca\/\">Biblioteca<\/a> durante il periodo di studio all\u2019Istituto e potranno prendere in presto film e dvd gratuitamente.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Iscrizione e diritto di recesso<\/strong><\/h3>\n<p>Entro 5 giorni lavorativi si ricever\u00e0 una fattura via e-mail per completare l\u2019iscrizione. Non \u00e8 purtroppo possibile il pagamento in contanti.<br \/>\nL\u2019iscrizione al corso si considera definitiva soltanto a pagamento avvenuto.<br \/>\nAll\u2019iscrizione si applica un diritto di recesso di 14 giorni. Oltre questa scadenza non saranno effettuati rimborsi.<br \/>\nSe le lezioni vengono cancellate dal docente, la lezione verr\u00e0 recuperara a fine corso. L\u2019Istituto manterr\u00e0, per quanto possibile, lo stesso giorno\/orario.<br \/>\nSe lo studente perde una lezione, la lezione persa non sar\u00e0 considerata \u2018credito\u2019 da utilizzare in futuro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Per maggiori informazioni:<br \/>\n<\/strong>La segreteria dei corsi \u00e8 aperta al pubblico tutti i giorni dalle 10.00 alle 12.00 e dalle 14:00 alle 16:00.<br \/>\n\u00c8 possibile contattare la segreteria negli stessi orari al numero\u00a0<strong>020-6263987.<br \/>\n<\/strong>L\u2019indirizzo e-mail della segreteria \u00e8\u00a0<a href=\"mailto:corsilingua.iicamsterdam@esteri.it\"><strong>corsilingua.iicamsterdam@esteri.it.<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Ami la lingua Italiana e vuoi migliorare o approfondire la tua grammatica? L&#8217;Istituto di Cultura Italiana offre una serie di sei incontri focalizzati sugli aspetti grammaticali pi\u00f9 utilizzati e allo stesso tempo pi\u00f9 ostici di questa bellissima lingua. Se vuoi iscriverti a tutti i 8 incontri clicca qui Se vuoi iscriverti al singolo incontro clicca [&hellip;]","protected":false},"author":15,"featured_media":0,"parent":42,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17996","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/pages\/17996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=17996"}],"version-history":[{"count":7,"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/pages\/17996\/revisions"}],"predecessor-version":[{"id":23552,"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/pages\/17996\/revisions\/23552"}],"up":[{"embeddable":true,"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/pages\/42"}],"wp:attachment":[{"href":"https:\/\/iicamsterdam.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=17996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}